{"id":10,"date":"2024-07-03T11:44:14","date_gmt":"2024-07-03T09:44:14","guid":{"rendered":"https:\/\/www.studiomattibeccaria.com\/?page_id=10"},"modified":"2026-02-25T17:31:49","modified_gmt":"2026-02-25T16:31:49","slug":"home","status":"publish","type":"page","link":"https:\/\/www.studiomattibeccaria.com\/","title":{"rendered":"Home"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:600px;aspect-ratio:unset;\"><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-52\" alt=\"\" src=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/themes\/exs-medic\/assets\/img\/3.jpg\" data-object-fit=\"cover\"\/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"mb-3 has-huge-font-size\"><strong>UN TEAM DI PROFESSIONISTI PER IL TUO BENESSERE.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-main-background-color has-background wp-element-button\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/metodo\/\">IL NOSTRO METODO<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-dark-background-color has-background wp-element-button\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/contatti\/\">PRENOTA<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\">Professionalita&#8217;<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><strong>Mettiamo in primo piano la persona con la medicina funzionale integrata.<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-main-color has-alpha-channel-opacity has-main-background-color has-background center mt-2\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-columns  cols-single-sm gap-30 pt-3 pb-2 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Ginecologia integrata<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center mb-05\">Approccio integrato per la <strong>gestione delle condizioni ginecologiche comuni<\/strong>, squilibri ormonali e gestione della menopausa con terapie ormonali bioidentiche.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Fisioterapia<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center mb-05\">L\u2019obiettivo del fisioterapista \u00e8 quello di <strong>ricercare la causa e non il sintomo del problema<\/strong>, spesso infatti la causa del dolore trova la sua locazione lontano dalla zona dolorosa<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Nutrizione<\/strong><\/h4>\n\n\n\n<p>Dimagrimento Allergie, Intolleranze, infiammazione da cibo Sintomatologie specifiche (emicrania, disturbi digestivi\u2026) Patologie croniche Squilibri ormonali (disfunzioni tiroidee, endometriosi, PCOS, alterazioni del ciclo mestruale\u2026)<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group section l m pb-3 pt-5 is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\">IL NOSTRO METODO<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Il nostro gruppo \u00e8 finalizzato ad un progetto di salute e benessere ispirato dai principi della<br>medicina funzionale, che si avvicina al paziente con un approccio olistico, mirato a valutare le<br>cause che determinano la malattia.<br>Ci avviciniamo al paziente accogliendolo e accompagnandolo nel suo percorso di miglioramento<br>della salute, il paziente si sente coccolato e capito perch\u00e9 il rapporto di fiducia che si instaura \u00e8 forte<br>e trasparente.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-main-color has-alpha-channel-opacity has-main-background-color has-background center mt-2\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-group section l m pb-6 is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" id=\"<a-href=&quot;https:\/\/www.doctolib.it\/ginecologo-ostetrico\/milano\/cristina-beccaria\/booking?source=external_referral&amp;utm_campaign=website-button&amp;utm_source=cristina-beccaria-website-button&amp;utm_medium=referral&amp;utm_content=withoutpreview-blue-floating-bottom-right&amp;utm_term=cristina-beccaria&quot;-style=&quot;display:flex;text-align:center;background-color:-107ACA;color:-ffffff;font-size:14px;overflow:hidden;font-family:Roboto,-sans-serif;box-sizing:border-box;align-items:center;padding:0-24px;z-index:1000;height:48px;text-decoration:none;position:fixed;bottom:16px;right:16px;border-bottom-left-radius:none;border-bottom-right-radius:none;border-top-left-radius:4px;border-top-right-radius:4px;border-radius:24px&quot;-target=&quot;_blank&quot;&gt;-<!-----&gt;Prenota-un-appuntamento-online<!-----&gt;-<img-style=&quot;vertical-align:middle;width:auto;height:19px&quot;-src=&quot;https:\/\/pro.doctolib.it\/external_button\/doctolib-white-transparent.png&quot;-alt=&quot;Doctolib&quot;\/&gt;<\/a&gt;\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-center\"><div class=\"wp-block-media-text__content\">\n<p class=\"is-style-small-text\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\">servizi e discipline<\/mark><\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visita Ginecologica Integrata;<\/li>\n\n\n\n<li>Visita Nutrizionale funzionale;<\/li>\n\n\n\n<li>Visita e trattamento fisioterapico.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list styled\">\n<li>Ozonoterapia<\/li>\n\n\n\n<li>Careless Flow<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list styled\">\n<li>Wega TEST<\/li>\n\n\n\n<li>Ormoni bioidentici<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/themes\/exs-medic\/assets\/img\/1.jpg\" alt=\"\" class=\"wp-image-23 size-full\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group  pt-5 pb-3 is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center mb-05\">LA SALUTE ED IL BENESSERE AL CENTRO<\/h2>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Ci occupiamo della tua salute con professionalit,  garantendo <strong>soluzioni su misura per il tuo benessere<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity center mt-2\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading is-style-circle-bg has-huge-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\">1<\/mark><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"margin-top:1px;margin-bottom:15px\">Professionalita&#8217;<\/h4>\n\n\n\n<p>Operiamo con professionalit\u00e0 ed offriamo ai nostri pazienti un\u2019esperienza di <strong>cura di alta qualit\u00e0<\/strong>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading is-style-circle-bg has-huge-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\">2<\/mark><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"margin-top:1px;margin-bottom:15px\">Unicita&#8217;<\/h4>\n\n\n\n<p>Mettiamo in primo piano l\u2019<strong>unicit\u00e0 di ogni persona<\/strong> per un approccio di cura su misura.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading is-style-circle-bg has-huge-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\">3<\/mark><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"margin-top:1px;margin-bottom:15px\">Confronto <\/h4>\n\n\n\n<p>Promuoviamo l\u2019ascolto attivo e il <strong>costante confronto<\/strong> con il paziente a 360\u00b0.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/contatti\/\">PRENOTA<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-arrow\"><a class=\"wp-block-button__link has-main-background-color has-background wp-element-button\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/metodo\/\">IL NOSTRO METODO<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-left is-style-default has-dark-muted-color has-text-color has-link-color has-normal-font-size wp-elements-9c2e96b675efa0aa3616023a104dee3d\"><strong>I NOSTRI ULTIMI ARTICOLI<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.34%\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.34%\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n<\/div>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-4 wp-block-latest-posts\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/2025\/12\/02\/terapia-ormonale-sostitutiva-fda-rimuove-gli-alert-sui-rischi-oncologici-e-cardiovascolari\/\">Terapia ormonale sostitutiva, Fda rimuove gli alert sui rischi oncologici e cardiovascolari<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/2025\/10\/08\/alimenti-ultra-processati-le-disfunzioni-endocrine-non-dipendono-dalle-calorie-assunte\/\">Alimenti ultra-processati: le disfunzioni endocrine non dipendono dalle calorie assunte<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/2025\/10\/08\/menopausa-studio-identifica-variabili-che-mettono-a-rischio-di-soffrire-di-ansia-e-depressione\/\">Menopausa, studio identifica variabili che mettono a rischio di soffrire di ansia e depressione<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/www.studiomattibeccaria.com\/index.php\/2025\/06\/24\/lesercizio-fisico-stabilizza-la-vitamina-d-anche-senza-integratori-o-perdita-di-peso\/\">L\u2019ESERCIZIO FISICO STABILIZZA LA VITAMINA D ANCHE SENZA INTEGRATORI O PERDITA DI PESO<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Professionalita&#8217; Mettiamo in primo piano la persona con la medicina funzionale integrata. Ginecologia integrata Approccio integrato per la gestione delle condizioni ginecologiche comuni, squilibri ormonali e gestione della menopausa con terapie ormonali bioidentiche. Fisioterapia L\u2019obiettivo del fisioterapista \u00e8 quello di ricercare la causa e non il sintomo del problema, spesso infatti la causa del dolore trova la sua locazione lontano<span class=\"more-dots\">&#8230;<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/no-sidebar-no-title.php","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":26,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":235,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions\/235"}],"wp:attachment":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}