{"id":11,"date":"2024-07-03T11:44:14","date_gmt":"2024-07-03T09:44:14","guid":{"rendered":"https:\/\/www.studiomattibeccaria.com\/?page_id=11"},"modified":"2025-01-14T15:14:16","modified_gmt":"2025-01-14T14:14:16","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/www.studiomattibeccaria.com\/index.php\/chi-siamo\/","title":{"rendered":"CHI SIAMO"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\">Ginecologa Cristina Beccaria<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"679\" height=\"1024\" src=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001-679x1024.jpg\" alt=\"\" class=\"wp-image-86\" style=\"width:331px;height:auto\" srcset=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001-679x1024.jpg 679w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001-199x300.jpg 199w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001-768x1158.jpg 768w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001-1019x1536.jpg 1019w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001-567x855.jpg 567w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240627-WA0001.jpg 1061w\" sizes=\"auto, (max-width: 679px) 100vw, 679px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center\">Ho prestato consulenza specialista presso il Policlinico San Matteo di Pavia (divisione di ostetricia e ginecologia), ho lavorato presso l\u2019ospedale civile di Voghera dal 1993 al 2010. Attualmente eseguo libera professione in ginecologia e ostetricia occupandomi anche di medicina funzionale\/ regolatoria e di ozonoterapia. Al centro della mia attenzione c\u2019\u00e8 la salute della donna a 360\u00b0 con la ricerca della causa e non la sola valutazione del sintomo. Mi occupo anche di fitoterapia e omeopatia<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-main-color has-alpha-channel-opacity has-main-background-color has-background center mt-2\"\/>\n\n\n\n<div class=\"wp-block-columns  cols-single-sm gap-30 pt-3 pb-2 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Dott. Fabrizio Matti <\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center mb-05\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"980\" src=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002-1024x980.jpg\" alt=\"\" class=\"wp-image-88\" style=\"width:325px;height:auto\" srcset=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002-1024x980.jpg 1024w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002-300x287.jpg 300w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002-768x735.jpg 768w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002-1536x1470.jpg 1536w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002-894x855.jpg 894w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240709-WA0002.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-arrow-transparent\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">OZONOTERAPIA<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Dott. Nicolo&#8217; Matti<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center mb-05\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"1024\" src=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005-673x1024.jpg\" alt=\"\" class=\"wp-image-87\" style=\"width:208px;height:auto\" srcset=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005-673x1024.jpg 673w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005-197x300.jpg 197w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005-768x1169.jpg 768w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005-1009x1536.jpg 1009w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005-562x855.jpg 562w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/IMG-20240703-WA0005.jpg 1051w\" sizes=\"auto, (max-width: 673px) 100vw, 673px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-arrow-transparent\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">FISIOTERAPIA<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns  cols-single-sm gap-30 pb-6 pt-3 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Dott.ssa Melissa Mantelli<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center mb-05\">I<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"350\" src=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/Foto-CV-JPEG.jpg\" alt=\"\" class=\"wp-image-93\" srcset=\"https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/Foto-CV-JPEG.jpg 312w, https:\/\/www.studiomattibeccaria.com\/wp-content\/uploads\/2025\/01\/Foto-CV-JPEG-267x300.jpg 267w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-arrow-transparent\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">NUTRIZIONISTA<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading has-text-align-center mt-0 mb-05\"><strong>Dott.ssa Marchesi Cristina<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center mb-05\"><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-arrow-transparent\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">FISIOTERAPIA E RIABILITAZIONE<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator alignfull has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-group  pt-5 pb-3 is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center mb-05\"><\/h2>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Lo studio si avvale di diversi professionisti nei vari ambiti della cura della persona con un <strong>approccio integrato e personalizzato<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Lavoriamo insieme per raggiungere il benessere del paziente<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity center mt-2\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-columns pt-1 pb-1 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile gap-15 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\">\n<h4 class=\"wp-block-heading is-style-circle-bg has-normal-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\"><\/mark><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" style=\"margin-bottom:0.5em\">GINECOLOGIA INTEGRATA<\/h4>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile gap-15 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\">\n<h4 class=\"wp-block-heading is-style-circle-bg has-normal-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\"><\/mark><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" style=\"margin-bottom:0.5em\">NUTRIZIONE FUNZIONALE<\/h4>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile gap-15 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\">\n<h4 class=\"wp-block-heading is-style-circle-bg has-normal-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\"><\/mark><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" style=\"margin-bottom:0.5em\">OZONOTERAPIA<\/h4>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns pt-1 pb-1 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile gap-15 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\">\n<h4 class=\"wp-block-heading is-style-circle-bg has-normal-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\"><\/mark><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile gap-15 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\">\n<h4 class=\"wp-block-heading is-style-circle-bg has-normal-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\"><\/mark><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h4 class=\"wp-block-heading\" style=\"margin-bottom:0.5em\">FISIOTERAPIA E RIABILITAZIONE<\/h4>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile gap-15 is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40px\">\n<h4 class=\"wp-block-heading is-style-circle-bg has-normal-font-size\"><mark style=\"background-color:var(--colorMain)\" class=\"has-inline-color has-light-color\"><\/mark><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ginecologa Cristina Beccaria Ho prestato consulenza specialista presso il Policlinico San Matteo di Pavia (divisione di ostetricia e ginecologia), ho lavorato presso l\u2019ospedale civile di Voghera dal 1993 al 2010. Attualmente eseguo libera professione in ginecologia e ostetricia occupandomi anche di medicina funzionale\/ regolatoria e di ozonoterapia. Al centro della mia attenzione c\u2019\u00e8 la salute della donna a 360\u00b0 con<span class=\"more-dots\">&#8230;<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":4,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":95,"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/pages\/11\/revisions\/95"}],"wp:attachment":[{"href":"https:\/\/www.studiomattibeccaria.com\/index.php\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}